{"id":5991,"date":"2019-05-11T15:43:45","date_gmt":"2019-05-11T13:43:45","guid":{"rendered":"https:\/\/sysmatec.ch\/produit\/enregistreur-de-temperature-et-humidite-el-21cfr-2-lcd-compatible-21cfr\/"},"modified":"2022-10-25T19:14:19","modified_gmt":"2022-10-25T17:14:19","slug":"temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel","status":"publish","type":"product","link":"https:\/\/sysmatec.ch\/de\/Produkt\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/","title":{"rendered":"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel"},"content":{"rendered":"<ul>\n<li type=\"disc\">mit LCD-Bildschirm<\/li>\n<li type=\"disc\">Taupunkt<\/li>\n<li type=\"disc\">EasyLog 21CFR Software als kostenloser Download zur Verf\u00fcgung<\/li>\n<li type=\"disc\">Weisen Sie einzelnen Benutzern mit bestimmten Berechtigungen zu\n<ul>\n<li type=\"disc\">Voll Software &amp; Sitzungsdaten mit Audit-Trails<\/li>\n<li type=\"disc\">Mail-Benachrichtigung bei fehlgeschlagenen Login<\/li>\n<li type=\"disc\">Digitale Unterschrift zu alle Berichte<\/li>\n<li type=\"disc\">Hinzuf\u00fcgen von Kommentaren<\/li>\n<\/ul>\n<\/li>\n<li type=\"disc\">Temperaturbereich: -35 bis + 80 \u00b0 C<\/li>\n<li type=\"disc\">Genauigkeit: +\/- 0.4 \u00b0 C<\/li>\n<li type=\"disc\">Luftfeuchtigkeit: 0 bis 100% rF<\/li>\n<li type=\"disc\">Genauigkeit: +\/- 2% RH<\/li>\n<li type=\"disc\">Hoher Kontrast LCD, mit zweieinhalb stellige Temperatur und Feuchte-Anzeigefunktion<\/li>\n<li type=\"disc\">Sofort, verz\u00f6gert und Push-to-Start Logging<\/li>\n<li>Speicherungsintervall: 10 Sec. bis 12 Std.<\/li>\n<li>Speicherkapazit\u00e4t: 16 382 Temperatur, 16 382 Feuchte<\/li>\n<li type=\"disc\">Akkulaufzeit: 2 Jahre (bei 25 \u00b0 C und 1 Minute Aufzeichnungsrate, LCD ein)<\/li>\n<li type=\"disc\">IP 67<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"VIiyi\" lang=\"de\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"de\" data-language-to-translate-into=\"fr\" data-phrase-index=\"4\" data-number-of-phrases=\"5\">Temperatur- und Feuchtedatenlogger mit USB-Schnittstelle, 21CFR.<\/span><\/span><\/p>\n","protected":false},"featured_media":5989,"template":"","meta":{"_crdt_document":""},"product_brand":[],"product_cat":[168,175],"product_tag":[],"class_list":{"0":"post-5991","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-datenlogger","7":"product_cat-feuchte","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel - Sysmatec<\/title>\n<meta name=\"description\" content=\"Temperatur- und Feuchtigkeitsschreiber mit interner Sonde. Kommunikation \u00fcber USB-Schnittstelle. 21CFR-konform.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel - Sysmatec\" \/>\n<meta property=\"og:description\" content=\"Temperatur- und Feuchtigkeitsschreiber mit interner Sonde. Kommunikation \u00fcber USB-Schnittstelle. 21CFR-konform.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/\" \/>\n<meta property=\"og:site_name\" content=\"Sysmatec\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T17:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sysmatec.ch\/wp-content\/uploads\/2019\/05\/Humidite_LascarEL21CFR2LCD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"97\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/\",\"url\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/\",\"name\":\"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel - Sysmatec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sysmatec.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Humidite_LascarEL21CFR2LCD.jpg\",\"datePublished\":\"2019-05-11T13:43:45+00:00\",\"dateModified\":\"2022-10-25T17:14:19+00:00\",\"description\":\"Temperatur- und Feuchtigkeitsschreiber mit interner Sonde. Kommunikation \u00fcber USB-Schnittstelle. 21CFR-konform.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sysmatec.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Humidite_LascarEL21CFR2LCD.jpg\",\"contentUrl\":\"https:\\\/\\\/sysmatec.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Humidite_LascarEL21CFR2LCD.jpg\",\"width\":185,\"height\":97},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/produit\\\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Aktivit\u00e4t von Sysmatec\",\"item\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/\",\"name\":\"Sysmatec\",\"description\":\"Equipement de laboratoire et logiciels\",\"publisher\":{\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/#organization\",\"name\":\"Sysmatec\",\"url\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sysmatec.ch\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/LogoSysmatec.jpg\",\"contentUrl\":\"https:\\\/\\\/sysmatec.ch\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/LogoSysmatec.jpg\",\"width\":301,\"height\":297,\"caption\":\"Sysmatec\"},\"image\":{\"@id\":\"https:\\\/\\\/sysmatec.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel - Sysmatec","description":"Temperatur- und Feuchtigkeitsschreiber mit interner Sonde. Kommunikation \u00fcber USB-Schnittstelle. 21CFR-konform.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/","og_locale":"de_DE","og_type":"article","og_title":"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel - Sysmatec","og_description":"Temperatur- und Feuchtigkeitsschreiber mit interner Sonde. Kommunikation \u00fcber USB-Schnittstelle. 21CFR-konform.","og_url":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/","og_site_name":"Sysmatec","article_modified_time":"2022-10-25T17:14:19+00:00","og_image":[{"width":185,"height":97,"url":"https:\/\/sysmatec.ch\/wp-content\/uploads\/2019\/05\/Humidite_LascarEL21CFR2LCD.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/","url":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/","name":"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel - Sysmatec","isPartOf":{"@id":"https:\/\/sysmatec.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/#primaryimage"},"image":{"@id":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/#primaryimage"},"thumbnailUrl":"https:\/\/sysmatec.ch\/wp-content\/uploads\/2019\/05\/Humidite_LascarEL21CFR2LCD.jpg","datePublished":"2019-05-11T13:43:45+00:00","dateModified":"2022-10-25T17:14:19+00:00","description":"Temperatur- und Feuchtigkeitsschreiber mit interner Sonde. Kommunikation \u00fcber USB-Schnittstelle. 21CFR-konform.","breadcrumb":{"@id":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/#primaryimage","url":"https:\/\/sysmatec.ch\/wp-content\/uploads\/2019\/05\/Humidite_LascarEL21CFR2LCD.jpg","contentUrl":"https:\/\/sysmatec.ch\/wp-content\/uploads\/2019\/05\/Humidite_LascarEL21CFR2LCD.jpg","width":185,"height":97},{"@type":"BreadcrumbList","@id":"https:\/\/sysmatec.ch\/de\/produit\/temperatur-feuchtedatenlogger-el-21cfr-2-lcd-21cfr-kompatibel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sysmatec.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Die Aktivit\u00e4t von Sysmatec","item":"https:\/\/sysmatec.ch\/de\/"},{"@type":"ListItem","position":3,"name":"Temperatur + Feuchtedatenlogger EL-21CFR-2-LCD, 21CFR-Kompatibel"}]},{"@type":"WebSite","@id":"https:\/\/sysmatec.ch\/de\/#website","url":"https:\/\/sysmatec.ch\/de\/","name":"Sysmatec","description":"Equipement de laboratoire et logiciels","publisher":{"@id":"https:\/\/sysmatec.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sysmatec.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sysmatec.ch\/de\/#organization","name":"Sysmatec","url":"https:\/\/sysmatec.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sysmatec.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/sysmatec.ch\/wp-content\/uploads\/2018\/11\/LogoSysmatec.jpg","contentUrl":"https:\/\/sysmatec.ch\/wp-content\/uploads\/2018\/11\/LogoSysmatec.jpg","width":301,"height":297,"caption":"Sysmatec"},"image":{"@id":"https:\/\/sysmatec.ch\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/product\/5991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/media\/5989"}],"wp:attachment":[{"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/media?parent=5991"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/product_brand?post=5991"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/product_cat?post=5991"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sysmatec.ch\/de\/wp-json\/wp\/v2\/product_tag?post=5991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}